{"id":1119,"date":"2023-12-20T14:38:47","date_gmt":"2023-12-20T13:38:47","guid":{"rendered":"https:\/\/www.maquettesdebateaux.com\/produit\/muscadet\/"},"modified":"2023-12-20T14:38:47","modified_gmt":"2023-12-20T13:38:47","slug":"muscadet","status":"publish","type":"product","link":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/","title":{"rendered":"Muscadet"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Model numbered \u2013 delivered with a certificate of authenticity<\/p>\n<p>\u2022 MUSCADET nicknamed the \u201cugly small duck\u201d was designed by the architect Philippe HARLE and launched in 1963 by AUBIN Shipyards .<br \/>\n\u2022 Produced about 1000 copies, the production was stopped in 1979, it measures 6.40 meters, with an option keelboat or dinghy, grated a mainsail (10.65 m2) and a spinnaker (34.40 m2) \u2026<br \/>\n\u2022 Philippe HARLE was a faithful reader of \u201ccanard enchain\u00e9\u201d (french newspapers)<br \/>\n<strong>[su_table responsive=\"yes\"]<\/strong><\/p>\n<table>\n<tbody>\n<tr style=\"font-weight: 600;\">\n<td>Sizle<\/td>\n<td>Scale<\/td>\n<td>Finishing<\/td>\n<td>Working Time<\/td>\n<\/tr>\n<tr>\n<td>38cm<\/td>\n<td>1\/18e<\/td>\n<td>Painted<\/td>\n<td>\/<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>[\/su_table]<\/strong><\/p>\n","protected":false},"featured_media":1105,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":""},"product_brand":[],"product_cat":[75],"product_tag":[],"class_list":{"0":"post-1119","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-regatta-souvenirs","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muscadet - Le village<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muscadet - Le village\" \/>\n<meta property=\"og:description\" content=\"Model numbered \u2013 delivered with a certificate of authenticity \u2022 MUSCADET nicknamed the \u201cugly small duck\u201d was designed by the architect Philippe HARLE and launched in 1963 by AUBIN Shipyards . \u2022 Produced about 1000 copies, the production was stopped in 1979, it measures 6.40 meters, with an option keelboat or dinghy, grated a mainsail (10.65 m2) and a spinnaker (34.40 m2) \u2026 \u2022 Philippe HARLE was a faithful reader of \u201ccanard enchain\u00e9\u201d (french newspapers)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/\" \/>\n<meta property=\"og:site_name\" content=\"Le village\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maquettesdebateaux.com\/wp-content\/uploads\/2023\/12\/maquette-muscadet-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/\",\"url\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/\",\"name\":\"Muscadet - Le village\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/maquette-muscadet-1.webp\",\"datePublished\":\"2023-12-20T13:38:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/maquette-muscadet-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/maquette-muscadet-1.webp\",\"width\":600,\"height\":400,\"caption\":\"Muscadet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/produit\\\/muscadet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Muscadet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/\",\"name\":\"Le village\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/#organization\",\"name\":\"Le village\",\"url\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-Le-Village-Maquettes-Bateaux.webp\",\"contentUrl\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-Le-Village-Maquettes-Bateaux.webp\",\"width\":270,\"height\":124,\"caption\":\"Le village\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maquettesdebateaux.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muscadet - Le village","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/","og_locale":"en_US","og_type":"article","og_title":"Muscadet - Le village","og_description":"Model numbered \u2013 delivered with a certificate of authenticity \u2022 MUSCADET nicknamed the \u201cugly small duck\u201d was designed by the architect Philippe HARLE and launched in 1963 by AUBIN Shipyards . \u2022 Produced about 1000 copies, the production was stopped in 1979, it measures 6.40 meters, with an option keelboat or dinghy, grated a mainsail (10.65 m2) and a spinnaker (34.40 m2) \u2026 \u2022 Philippe HARLE was a faithful reader of \u201ccanard enchain\u00e9\u201d (french newspapers)","og_url":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/","og_site_name":"Le village","og_image":[{"width":600,"height":400,"url":"https:\/\/www.maquettesdebateaux.com\/wp-content\/uploads\/2023\/12\/maquette-muscadet-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/","url":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/","name":"Muscadet - Le village","isPartOf":{"@id":"https:\/\/www.maquettesdebateaux.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/#primaryimage"},"image":{"@id":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maquettesdebateaux.com\/wp-content\/uploads\/2023\/12\/maquette-muscadet-1.webp","datePublished":"2023-12-20T13:38:47+00:00","breadcrumb":{"@id":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/#primaryimage","url":"https:\/\/www.maquettesdebateaux.com\/wp-content\/uploads\/2023\/12\/maquette-muscadet-1.webp","contentUrl":"https:\/\/www.maquettesdebateaux.com\/wp-content\/uploads\/2023\/12\/maquette-muscadet-1.webp","width":600,"height":400,"caption":"Muscadet"},{"@type":"BreadcrumbList","@id":"https:\/\/www.maquettesdebateaux.com\/en\/produit\/muscadet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.maquettesdebateaux.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.maquettesdebateaux.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Muscadet"}]},{"@type":"WebSite","@id":"https:\/\/www.maquettesdebateaux.com\/en\/#website","url":"https:\/\/www.maquettesdebateaux.com\/en\/","name":"Le village","description":"","publisher":{"@id":"https:\/\/www.maquettesdebateaux.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maquettesdebateaux.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.maquettesdebateaux.com\/en\/#organization","name":"Le village","url":"https:\/\/www.maquettesdebateaux.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maquettesdebateaux.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.maquettesdebateaux.com\/wp-content\/uploads\/2021\/02\/Logo-Le-Village-Maquettes-Bateaux.webp","contentUrl":"https:\/\/www.maquettesdebateaux.com\/wp-content\/uploads\/2021\/02\/Logo-Le-Village-Maquettes-Bateaux.webp","width":270,"height":124,"caption":"Le village"},"image":{"@id":"https:\/\/www.maquettesdebateaux.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/product\/1119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/comments?post=1119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/media\/1105"}],"wp:attachment":[{"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/media?parent=1119"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/product_brand?post=1119"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/product_cat?post=1119"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.maquettesdebateaux.com\/en\/wp-json\/wp\/v2\/product_tag?post=1119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}